{"id":2470,"date":"2022-04-26T13:15:37","date_gmt":"2022-04-26T16:15:37","guid":{"rendered":"https:\/\/colmed1.org.ar\/?p=2470"},"modified":"2022-04-26T16:54:04","modified_gmt":"2022-04-26T19:54:04","slug":"curso-superior-bienal-de-especializacion-en-administracion-sanitaria-hospitalaria-1o-ano","status":"publish","type":"post","link":"https:\/\/colmed1.org.ar\/web\/index.php\/2022\/04\/26\/curso-superior-bienal-de-especializacion-en-administracion-sanitaria-hospitalaria-1o-ano\/","title":{"rendered":"Curso Superior Bienal de Especializaci\u00f3n en ADMINISTRACI\u00d3N SANITARIA HOSPITALARIA-1\u00ba a\u00f1o"},"content":{"rendered":"\n<p>El Colegio de M\u00e9dicos de la Provincia de Buenos Aires, Distrito I, informa a sus matriculados que se encuentra abierta la inscripci\u00f3n al Curso Superior Bienal de Especializaci\u00f3n en ADMINISTRACI\u00d3N SANITARIA HOSPITALARIA-1\u00ba a\u00f1o.<\/p>\n\n\n\n<p>La actividad comenzar\u00e1 el jueves 5 de mayo.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/colmed1.org.ar\/wp-content\/uploads\/2022\/04\/afiche-administracion-2022-v-2.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de Incrustado de afiche-administracion-2022-v-2..\"><\/object><a id=\"wp-block-file--media-3325fbdd-203e-4ca9-adb4-7a5b6963adaa\" href=\"https:\/\/colmed1.org.ar\/wp-content\/uploads\/2022\/04\/afiche-administracion-2022-v-2.pdf\">afiche-administracion-2022-v-2<\/a><a href=\"https:\/\/colmed1.org.ar\/wp-content\/uploads\/2022\/04\/afiche-administracion-2022-v-2.pdf\" class=\"wp-block-file__button\" download aria-describedby=\"wp-block-file--media-3325fbdd-203e-4ca9-adb4-7a5b6963adaa\">Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Colegio de M\u00e9dicos de la Provincia de Buenos Aires, Distrito I, informa a sus matriculados que se encuentra abierta la inscripci\u00f3n al Curso Superior Bienal de Especializaci\u00f3n en ADMINISTRACI\u00d3N SANITARIA HOSPITALARIA-1\u00ba a\u00f1o. La actividad comenzar\u00e1 el jueves 5 de mayo.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[10,12],"tags":[],"class_list":["post-2470","post","type-post","status-publish","format-standard","hentry","category-principal","category-secunadaria"],"_links":{"self":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=2470"}],"version-history":[{"count":3,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2470\/revisions"}],"predecessor-version":[{"id":2481,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2470\/revisions\/2481"}],"wp:attachment":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=2470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=2470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=2470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}