{"id":2654,"date":"2022-07-12T09:04:28","date_gmt":"2022-07-12T12:04:28","guid":{"rendered":"https:\/\/colmed1.org.ar\/?p=2654"},"modified":"2022-07-12T09:04:30","modified_gmt":"2022-07-12T12:04:30","slug":"residencia-en-clinica-medica-2022-2023-en-instituto-de-diagnostico-de-la-plata","status":"publish","type":"post","link":"https:\/\/colmed1.org.ar\/web\/index.php\/2022\/07\/12\/residencia-en-clinica-medica-2022-2023-en-instituto-de-diagnostico-de-la-plata\/","title":{"rendered":"Residencia en Cl\u00ednica M\u00e9dica 2022\/2023 en Instituto de Diagn\u00f3stico de La Plata"},"content":{"rendered":"\n<p>El colegio de M\u00e9dicos de la Provincia de Buenos Aires, Distrito I, informa a sus matriculados que se encuentra abierta la inscripci\u00f3n a la Residencia en Cl\u00ednica M\u00e9dica 2022\/2023 en Instituto de Diagn\u00f3stico de La Plata.<\/p>\n\n\n<!-- PDF Embedder: Please provide an \"URL\" attribute in your shortcode. -->\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-6173be87-5eca-45d3-a786-821f4cc826a2\" href=\"https:\/\/colmed1.org.ar\/wp-content\/uploads\/2022\/07\/Residencia-a-clinica-vale.png\">Residencia-a-clinica-vale<\/a><a href=\"https:\/\/colmed1.org.ar\/wp-content\/uploads\/2022\/07\/Residencia-a-clinica-vale.png\" class=\"wp-block-file__button\" download aria-describedby=\"wp-block-file--media-6173be87-5eca-45d3-a786-821f4cc826a2\">Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El colegio de M\u00e9dicos de la Provincia de Buenos Aires, Distrito I, informa a sus matriculados que se encuentra abierta la inscripci\u00f3n a la Residencia en Cl\u00ednica M\u00e9dica 2022\/2023 en Instituto de Diagn\u00f3stico de La Plata.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-2654","post","type-post","status-publish","format-standard","hentry","category-principal"],"_links":{"self":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=2654"}],"version-history":[{"count":1,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2654\/revisions"}],"predecessor-version":[{"id":2656,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2654\/revisions\/2656"}],"wp:attachment":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=2654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=2654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=2654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}