{"id":2688,"date":"2022-07-15T18:04:59","date_gmt":"2022-07-15T21:04:59","guid":{"rendered":"https:\/\/colmed1.org.ar\/?p=2688"},"modified":"2022-07-15T18:05:02","modified_gmt":"2022-07-15T21:05:02","slug":"nueva-escala-salarial-aprobada-por-el-ministerio-de-salud-de-la-pcia-de-bs-as-para-medicos-residentes","status":"publish","type":"post","link":"https:\/\/colmed1.org.ar\/web\/index.php\/2022\/07\/15\/nueva-escala-salarial-aprobada-por-el-ministerio-de-salud-de-la-pcia-de-bs-as-para-medicos-residentes\/","title":{"rendered":"NUEVA ESCALA SALARIAL APROBADA POR EL MINISTERIO DE SALUD DE LA PCIA DE BS. AS. PARA MEDICOS RESIDENTES"},"content":{"rendered":"\n<p>El Colegio de M\u00e9dicos de la Provincia de Buenos Aires, Distrito I, informa a sus matriculados los montos netos que deber\u00e1n percibir los residentes de las distintas unidades acad\u00e9micas privadas avaladas por el Colegio de M\u00e9dicos de la Pcia. de Bs. As., sujeto a modificaciones de paritarias fijadas por el Ministerio de Salud Provincial.-<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"973\" src=\"https:\/\/colmed1.org.ar\/wp-content\/uploads\/2022\/07\/ESCALA-SALARIAL-1-1024x973.jpg\" alt=\"\" class=\"wp-image-2685\" srcset=\"https:\/\/colmed1.org.ar\/wp-content\/uploads\/2022\/07\/ESCALA-SALARIAL-1-980x931.jpg 980w, https:\/\/colmed1.org.ar\/wp-content\/uploads\/2022\/07\/ESCALA-SALARIAL-1-480x456.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Colegio de M\u00e9dicos de la Provincia de Buenos Aires, Distrito I, informa a sus matriculados los montos netos que deber\u00e1n percibir los residentes de las distintas unidades acad\u00e9micas privadas avaladas por el Colegio de M\u00e9dicos de la Pcia. de Bs. As., sujeto a modificaciones de paritarias fijadas por el Ministerio de Salud Provincial.-<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[10,12],"tags":[],"class_list":["post-2688","post","type-post","status-publish","format-standard","hentry","category-principal","category-secunadaria"],"_links":{"self":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=2688"}],"version-history":[{"count":1,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2688\/revisions"}],"predecessor-version":[{"id":2689,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2688\/revisions\/2689"}],"wp:attachment":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=2688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=2688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=2688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}