{"id":2691,"date":"2022-07-18T14:31:36","date_gmt":"2022-07-18T17:31:36","guid":{"rendered":"https:\/\/colmed1.org.ar\/?p=2691"},"modified":"2022-07-18T14:31:38","modified_gmt":"2022-07-18T17:31:38","slug":"curso-de-auditoria-medica-y-gestion-de-la-calidad-de-la-atencion-medica","status":"publish","type":"post","link":"https:\/\/colmed1.org.ar\/web\/index.php\/2022\/07\/18\/curso-de-auditoria-medica-y-gestion-de-la-calidad-de-la-atencion-medica\/","title":{"rendered":"Curso de Auditoria Medica y Gesti\u00f3n de la Calidad de la atenci\u00f3n Medica"},"content":{"rendered":"\n<p>El colegio de M\u00e9dicos Distrito 1 invita a participar del Curso de Auditoria Medica y Gesti\u00f3n de la Calidad de la Atenci\u00f3n Medica, que comienza el 3 de agosto con modalidad semanal, en la sede del Colegio: Calle 51 nro 723.<\/p>\n\n\n<a href=\"https:\/\/colmed1.org.ar\/wp-content\/uploads\/2022\/07\/auditoria-medica-2022-14.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"top\" data-toolbar-fixed=\"off\">auditoria-medica-2022-14<\/a>\n<p class=\"wp-block-pdfemb-pdf-embedder-viewer\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de 3 de agosto al 30 de noviembre<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-2691","post","type-post","status-publish","format-standard","hentry","category-secunadaria"],"_links":{"self":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=2691"}],"version-history":[{"count":2,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2691\/revisions"}],"predecessor-version":[{"id":2694,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2691\/revisions\/2694"}],"wp:attachment":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=2691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=2691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=2691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}