{"id":2822,"date":"2022-10-17T13:15:44","date_gmt":"2022-10-17T16:15:44","guid":{"rendered":"https:\/\/colmed1.org.ar\/?p=2822"},"modified":"2022-10-17T13:15:46","modified_gmt":"2022-10-17T16:15:46","slug":"ciclo-talleres-la-historia-argentina-desde-el-cine-y-la-literatura-2","status":"publish","type":"post","link":"https:\/\/colmed1.org.ar\/web\/index.php\/2022\/10\/17\/ciclo-talleres-la-historia-argentina-desde-el-cine-y-la-literatura-2\/","title":{"rendered":"Ciclo Talleres: La Historia Argentina desde el cine y la Literatura"},"content":{"rendered":"\n<p>El Colegio de M\u00e9dicos de la Provincia de Buenos Aires, Distrito I, invita a sus matriculados a participar del \u201cCiclo Talleres: La Historia Argentina desde el cine y la Literatura\u201d.<\/p>\n\n\n\n<p>La actividad tendr\u00e1 inicio el dos de noviembre y se realizar\u00e1 todos los mi\u00e9rcoles de 19 a 20.30 hs.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"885\" src=\"https:\/\/colmed1.org.ar\/wp-content\/uploads\/2022\/10\/Afiche-HISTORIA.jpg\" alt=\"\" class=\"wp-image-2823\" srcset=\"https:\/\/colmed1.org.ar\/wp-content\/uploads\/2022\/10\/Afiche-HISTORIA.jpg 800w, https:\/\/colmed1.org.ar\/wp-content\/uploads\/2022\/10\/Afiche-HISTORIA-480x531.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Colegio de M\u00e9dicos de la Provincia de Buenos Aires, Distrito I, invita a sus matriculados a participar del \u201cCiclo Talleres: La Historia Argentina desde el cine y la Literatura\u201d. La actividad tendr\u00e1 inicio el dos de noviembre y se realizar\u00e1 todos los mi\u00e9rcoles de 19 a 20.30 hs.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-2822","post","type-post","status-publish","format-standard","hentry","category-principal"],"_links":{"self":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=2822"}],"version-history":[{"count":1,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2822\/revisions"}],"predecessor-version":[{"id":2824,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2822\/revisions\/2824"}],"wp:attachment":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=2822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=2822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=2822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}