{"id":3107,"date":"2023-06-07T19:52:42","date_gmt":"2023-06-07T22:52:42","guid":{"rendered":"https:\/\/colmed1.org.ar\/?p=3107"},"modified":"2023-06-07T19:52:43","modified_gmt":"2023-06-07T22:52:43","slug":"el-abandono-del-gobierno-atenta-contra-la-vida-de-los-pacientes-y-la-de-los-profesionales-de-la-salud","status":"publish","type":"post","link":"https:\/\/colmed1.org.ar\/web\/index.php\/2023\/06\/07\/el-abandono-del-gobierno-atenta-contra-la-vida-de-los-pacientes-y-la-de-los-profesionales-de-la-salud\/","title":{"rendered":"El abandono del Gobierno atenta contra la vida de los pacientes y la de los profesionales de la Salud"},"content":{"rendered":"\n<p>Desde el Distrito I del Colegio de M\u00e9dicos de la Provincia de Buenos Aires lamentamos profundamente el brutal hecho de violencia intrahospitalaria que sufri\u00f3 la Jefa de Guardia del Hospital de Ni\u00f1os \u201cSor Mar\u00eda Ludovica\u201d de la Ciudad de La Plata.<\/p>\n\n\n\n<p>La fuga de profesionales por los salarios paup\u00e9rrimos que otorga el gobierno provincial, la falta de insumos y aparatolog\u00eda, y las deficientes condiciones infraestructurales del hospital, son algunos de los condicionantes que dan como resultado salas de espera colapsadas, y profesionales exhaustos por la sobrecarga laboral, y el contexto de abandono y negligencia por parte de las autoridades.<\/p>\n\n\n\n<p>Desde esta instituci\u00f3n, conminamos al Ministerio de Salud de la Provincia de Buenos Aires a tomar medidas urgentes para revertir las condiciones infrahumanas en las que sobrevive y convive la Comunidad Sanitaria.&nbsp;<\/p>\n\n\n\n<p>En esta l\u00ednea, imploramos que abandonen la pr\u00e9dica y la confrontaci\u00f3n innecesaria, para considerar las funestas situaciones que viven a diario pacientes, y profesionales sanitarios, para actuar en consecuencia.<\/p>\n\n\n\n<p><em>La \u00fanica verdad, es la realidad.<\/em><\/p>\n\n\n\n<p><strong>MESA DIRECTIVA<\/strong><\/p>\n\n\n\n<p><em>Colegio de M\u00e9dicos de la Provincia de Buenos Aires \u2013 Distrito I<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el Distrito I del Colegio de M\u00e9dicos de la Provincia de Buenos Aires lamentamos profundamente el brutal hecho de violencia intrahospitalaria que sufri\u00f3 la Jefa de Guardia del Hospital de Ni\u00f1os \u201cSor Mar\u00eda Ludovica\u201d de la Ciudad de La Plata. La fuga de profesionales por los salarios paup\u00e9rrimos que otorga el gobierno provincial, la [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":3108,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[10,12],"tags":[],"class_list":["post-3107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-principal","category-secunadaria"],"_links":{"self":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/3107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=3107"}],"version-history":[{"count":1,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/3107\/revisions"}],"predecessor-version":[{"id":3109,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/3107\/revisions\/3109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/3108"}],"wp:attachment":[{"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=3107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=3107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colmed1.org.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=3107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}